{"id":73,"date":"2025-05-12T14:56:33","date_gmt":"2025-05-12T14:56:33","guid":{"rendered":"https:\/\/www.nollapiste.fi\/?page_id=73"},"modified":"2026-03-31T08:39:08","modified_gmt":"2026-03-31T08:39:08","slug":"etusivu","status":"publish","type":"page","link":"https:\/\/www.nollapiste.fi\/","title":{"rendered":"Etusivu"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_video_mp4=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/03\/Nollapiste-etusivu-video.mp4&#8243; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||94px||false|false&#8221; custom_padding_tablet=&#8221;0px||142px||false|false&#8221; custom_padding_phone=&#8221;0px||142px||false|false&#8221; background_last_edited=&#8221;on|phone&#8221; background_video_mp4_phone=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/03\/Nollapiste-etusivu-puhelin-video.mp4&#8243; background_enable_video_mp4_phone=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 2%|#ffffff 44%|rgba(255, 255, 255, 0.37) 74%|rgba(255,255,255,0) 85%&#8221; width=&#8221;113.4%&#8221; max_width=&#8221;2860px&#8221; custom_margin=&#8221;|auto||-14px||&#8221; custom_padding=&#8221;13px|||0px||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;181px||127px|||&#8221; custom_padding_tablet=&#8221;285px|||||&#8221; custom_padding_phone=&#8221;150px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Bangers||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;35px&#8221; text_letter_spacing=&#8221;9px&#8221; text_line_height=&#8221;1em&#8221; header_5_font=&#8221;Bangers||||||||&#8221; header_5_text_color=&#8221;#FFFFFF&#8221; header_5_font_size=&#8221;49px&#8221; header_5_line_height=&#8221;1em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;2px||-2px|||&#8221; custom_padding=&#8221;18px||21px|||&#8221; text_font_size_tablet=&#8221;35px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_5_font_size_phone=&#8221;27px&#8221; text_text_shadow_style=&#8221;preset1&#8243; text_text_shadow_color=&#8221;gcid-heading-color&#8221; header_5_text_shadow_style=&#8221;preset1&#8243; header_5_text_shadow_horizontal_length=&#8221;0.13em&#8221; header_5_text_shadow_vertical_length=&#8221;0.03em&#8221; header_5_text_shadow_blur_strength=&#8221;0.15em&#8221; header_5_text_shadow_color=&#8221;gcid-body-color&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;-17px&#8221; box_shadow_vertical=&#8221;16px&#8221; box_shadow_blur=&#8221;59px&#8221; box_shadow_spread=&#8221;35px&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22%93,%22gcid-heading-color%22:%91%22text_text_shadow_color%22%93,%22gcid-body-color%22:%91%22header_5_text_shadow_color%22%93}&#8221;]<\/p>\n<h5>Tervetuloa mocktailien valtakuntaan<\/h5>\n<p>t\u00e4\u00e4ll\u00e4 bailataan nollat taulussa<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;90px||9px|||&#8221; custom_padding_tablet=&#8221;90px||9px|||&#8221; custom_padding_phone=&#8221;20px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto|1px|auto||&#8221; custom_margin_tablet=&#8221;|auto|1px|auto||&#8221; custom_margin_phone=&#8221;|0px|1px|0px|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|151px|4px|160px||&#8221; custom_padding_tablet=&#8221;|0px|4px|||&#8221; custom_padding_phone=&#8221;|10px|20px|10px|false|false&#8221; module_alignment_tablet=&#8221;&#8221; module_alignment_phone=&#8221;center&#8221; module_alignment_last_edited=&#8221;on|phone&#8221; border_width_bottom=&#8221;3px&#8221; border_color_bottom=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; global_colors_info=&#8221;{%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22border_color_bottom%22%93}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;NOLLAPISTE&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Bangers|500||on|||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; title_font_size=&#8221;98px&#8221; title_letter_spacing=&#8221;9px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||0px|||&#8221; custom_padding=&#8221;146px|||||&#8221; custom_padding_tablet=&#8221;146px|||||&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;50px&#8221; title_text_shadow_style=&#8221;preset5&#8243; title_text_shadow_color=&#8221;gcid-33e338c4-dd9b-4b3a-bb88-a86a4fca0c7b&#8221; text_shadow_style=&#8221;preset1&#8243; text_shadow_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; global_colors_info=&#8221;{%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22text_shadow_color%22%93,%22gcid-33e338c4-dd9b-4b3a-bb88-a86a4fca0c7b%22:%91%22title_text_shadow_color%22%93,%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_cta title=&#8221;- Mocktailbaari -&#8221; button_url=&#8221;#top&#8221; admin_label=&#8221;Tittle, Paragraph &#038; Call To Action&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_font_size=&#8221;30px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.5em&#8221; use_background_color=&#8221;off&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Open Sans|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; background_layout=&#8221;light&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-10px||4px|167px||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; button_text_color_hover=&#8221;#ffffff&#8221; button_border_color_hover=&#8221;rgba(0,0,0,0)&#8221; button_border_radius_hover=&#8221;28px&#8221; button_letter_spacing_hover=&#8221;2px&#8221; button_bg_color_hover=&#8221;rgba(0,0,0,0.7)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22header_text_color%22,%22body_text_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;on&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;28px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;2px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0.7)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>Trendikk\u00e4\u00e4t alkoholittomat tuotteet joko itse nautittavaksi tai kauppasi\/ravintolasi valikoiman t\u00e4ydent\u00e4miseen.<\/p>\n<p>Mojito, Sex On the Beach, Riesling, Margarita&#8230; &#8211; mink\u00e4 drinkin ikin\u00e4 tahdotkin, l\u00f6ytyy se valikoimastamme alkoholittomana.<\/p>\n<p>[\/et_pb_cta][et_pb_button button_text=&#8221;Tuotteet&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; button_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; button_border_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; button_border_radius=&#8221;17px&#8221; button_font=&#8221;Oswald||||||||&#8221; global_colors_info=&#8221;{%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22button_text_color%22,%22button_border_color%22%93}&#8221;][\/et_pb_button][et_pb_social_media_follow disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||3px|||&#8221; custom_padding=&#8221;|||&#8221; mix_blend_mode=&#8221;multiply&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/share\/19CLoezket\/?mibextid=wwXIfr&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;rgba(160,160,160,0.8)&#8221; custom_margin=&#8221;|2%||2%&#8221; custom_padding=&#8221;12px|12px|12px|12px&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/nollapiste.fi?igsh=MXRjaHRvYWIwMjc2Yw%3D%3D&#038;utm_source=qr&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;rgba(160,160,160,0.8)&#8221; custom_margin=&#8221;|2%||2%&#8221; custom_padding=&#8221;12px|12px|12px|12px&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;tiktok&#8221; url=&#8221;https:\/\/www.tiktok.com\/@nollapiste.fi?is_from_webapp=1&#038;sender_device=pc&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(160,160,160,0.8)&#8221; custom_margin=&#8221;|2%||2%&#8221; custom_padding=&#8221;12px|12px|12px|12px&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]tiktok[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; background_video_mp4=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/03\/Nollapiste-mojito-puristus-video.mp4&#8243; border_radii=&#8221;off||80px|80px|&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||699px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|auto||auto|false|false&#8221; custom_padding=&#8221;82px||0px|||&#8221; custom_padding_tablet=&#8221;82px||0px|||&#8221; custom_padding_phone=&#8221;20px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_cta title=&#8221;Mocktailien uusi aikakausi on t\u00e4\u00e4ll\u00e4&#8221; button_url=&#8221;#top&#8221; admin_label=&#8221;Tittle, Paragraph &#038; Call To Action&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_font_size=&#8221;30px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.5em&#8221; use_background_color=&#8221;off&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Open Sans|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; background_layout=&#8221;light&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-10px||54px|167px||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; button_text_color_hover=&#8221;#ffffff&#8221; button_border_color_hover=&#8221;rgba(0,0,0,0)&#8221; button_border_radius_hover=&#8221;28px&#8221; button_letter_spacing_hover=&#8221;2px&#8221; button_bg_color_hover=&#8221;rgba(0,0,0,0.7)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22header_text_color%22,%22body_text_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;on&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;28px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;2px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0.7)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>Nollapiste tuo markkinoille uudenlaisen tavan nauttia klassisista cocktaileista \u2013 ilman alkoholia.<\/p>\n<p>Mocktailimme tarjoavat t\u00e4ydellisen makuel\u00e4myksen tilanteeseen kuin tilanteeseen, oli kyseess\u00e4 juhla, illanvietto, ravintolak\u00e4ynti tai tavallinen arkip\u00e4iv\u00e4. Me uskomme, ett\u00e4 hyv\u00e4 juoma on enemm\u00e4n kuin pelkk\u00e4 neste \u2013 se on tunnelma, hetki ja kokemus. Siksi meilt\u00e4 saa juomat, jotka tuovat t\u00e4m\u00e4n kokemuksen kaikille, ilman promilleja ja kompromisseja.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;357.8px&#8221; custom_padding=&#8221;0px||0px|||&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;gcid-33e338c4-dd9b-4b3a-bb88-a86a4fca0c7b&#8221; box_shadow_style=&#8221;preset5&#8243; box_shadow_horizontal=&#8221;-200px&#8221; box_shadow_vertical=&#8221;17px&#8221; box_shadow_spread=&#8221;29px&#8221; box_shadow_color=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; global_colors_info=&#8221;{%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22box_shadow_color%22%93,%22gcid-33e338c4-dd9b-4b3a-bb88-a86a4fca0c7b%22:%91%22border_color_all%22%93}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;FESTARIT&#8221; admin_label=&#8221;Juice Type&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; header_font_size=&#8221;20px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; body_font_size=&#8221;16px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_image=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/01\/Beige-Red-Retro-Typography-Cocktail-Print-Canvas-3.png&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;||9px|||&#8221; custom_padding=&#8221;23px|9px|3px|9px||&#8221; animation_style=&#8221;zoom&#8221; animation_delay=&#8221;100ms&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22body_quote_text_color%22,%22body_quote_text_color%22%93,%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22header_text_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22body_text_color%22%93}&#8221;]<\/p>\n<p>Festivaaleille Nollapiste tarjoaa modernin ja vastuullisen vaihtoehdon: laadukkaat, autenttiset ja tyylikk\u00e4\u00e4t mocktailit alkoholijuomien rinnalle. Mocktailimme ovat helposti tarjoiltavia, n\u00e4ytt\u00e4vi\u00e4 ja sopivat kaikille \u2013 niille, jotka haluavat nauttia tapahtumasta ilman alkoholia, mutta tinkim\u00e4tt\u00e4 el\u00e4myksest\u00e4 tai mausta.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Ravintolat&#8221; admin_label=&#8221;Juice Type&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; header_font_size=&#8221;20px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; body_font_size=&#8221;16px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_image=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/01\/Beige-Red-Retro-Typography-Cocktail-Print-Canvas-3.png&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;24px|5px|9px|7px||&#8221; animation_style=&#8221;zoom&#8221; animation_delay=&#8221;100ms&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22%93,%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22header_text_color%22,%22header_text_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22body_text_color%22,%22body_text_color%22%93}&#8221;]<\/p>\n<p>Ravintoloille tarjoamme laadukkaita alkoholittomia juomia joko valmiina t\u00f6lkeiss\u00e4 ja lasipulloissa tai ravintolassa valmistettavina mocktaileina k\u00e4tevien ja kokonaisvaltaisten drinkkipakettien avulla. N\u00e4in tarjoilusta tulee nopeaa ja vaivatonta \u2013 ilman kompromisseja maussa, laadussa tai esillepanossa.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Kaupat&#8221; admin_label=&#8221;Juice Type&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; header_font_size=&#8221;20px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; body_font_size=&#8221;16px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_image=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/01\/Beige-Red-Retro-Typography-Cocktail-Print-Canvas-3.png&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;31px|11px|9px|6px||&#8221; animation_style=&#8221;zoom&#8221; animation_delay=&#8221;100ms&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22,%22body_quote_text_color%22%93,%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22header_text_color%22,%22header_text_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22body_text_color%22,%22body_text_color%22%93}&#8221;]<\/p>\n<p>Kaupoille tarjoamme t\u00e4ysin uuden tuotekategorian \u2013 mocktailkaapin aloituspakkauksen, joka mahdollistaa helpon ja houkuttelevan tavan l\u00e4hesty\u00e4 mocktailien maailmaa. Tarjoamme my\u00f6s yksitt\u00e4isi\u00e4 t\u00f6lkkej\u00e4 ja lasipulloja, jotka tuovat hyllyihin laadukkaita tuotteita nopeasti kasvavasta juomakategoriasta.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;59px|auto||auto||&#8221; custom_padding=&#8221;||9px|||&#8221; border_width_bottom=&#8221;3px&#8221; border_color_bottom=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; global_colors_info=&#8221;{%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22border_color_bottom%22%93}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Tittle &#038; Paragraph&#8221; _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;Open Sans|600|||||||&#8221; text_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_font_size=&#8221;67px&#8221; header_2_font=&#8221;Oswald|||on|||||&#8221; header_2_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_2_font_size=&#8221;38px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.4em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;5px||40px||false|&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;0px||8px||false|&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22header_text_color%22,%22text_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Ota Yhteytt\u00e4<\/h2>\n<p>Haluatko mocktailit kauppaasi, ravintolaasi tai festareille tarjolle vai onko jotakin muuta kysytt\u00e4v\u00e4\u00e4? Ole rohkeasti meihin yhteydess\u00e4!<\/p>\n<p>Kerro my\u00f6s, miss\u00e4 haluaisit n\u00e4hd\u00e4 meid\u00e4t sek\u00e4 mik\u00e4 sinua kiinnostaa: festaribaarit, kauppa- vai ravintolatarjonta? Haluamme tiet\u00e4\u00e4, jotta voimme toteuttaa toiveesi!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_form captcha=&#8221;off&#8221; email=&#8221;tuuli.almila@remax.fi&#8221; title=&#8221;Yhteydenotto Nollapiste nettisivuilta&#8221; success_message=&#8221;Kiitos viestist\u00e4, palaamme asiaan pikimmiten!&#8221; disabled_on=&#8221;off|off|off&#8221; module_id=&#8221;et_pb_contact_form_0&#8243; _builder_version=&#8221;4.27.6&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; title_text_color=&#8221;RGBA(255,255,255,0)&#8221; title_font_size=&#8221;1px&#8221; form_field_font=&#8221;Open Sans|600|||||||&#8221; form_field_font_size=&#8221;14px&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; button_border_width=&#8221;3px&#8221; button_border_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Open Sans|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; title_font_size_phone=&#8221;1px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;rgba(51,51,51,0.1)&#8221; form_background_color=&#8221;rgba(255,255,255,0.4)&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22form_field_text_color%22,%22form_field_text_color%22%93,%22gcid-2ba1efb6-4031-47e4-a58d-f8150d56f0f2%22:%91%22form_field_background_color%22,%22form_field_background_color%22,%22form_field_background_color%22%93,%22gcid-primary-color%22:%91%22button_bg_color%22,%22button_bg_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22button_text_color%22,%22button_border_color%22%93}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Nimi&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;S\u00e4hk\u00f6posti&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Viesti&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;11px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_cta title=&#8221;Nollapiste n\u00e4htiin useilla festareilla vuonna 2025&#8243; button_url=&#8221;#top&#8221; admin_label=&#8221;Tittle, Paragraph &#038; Call To Action&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_font_size=&#8221;33px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; body_font_size=&#8221;16px&#8221; use_background_color=&#8221;off&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Open Sans|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; text_orientation=&#8221;right&#8221; background_layout=&#8221;light&#8221; custom_margin=&#8221;0px||1px|||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; button_text_color_hover=&#8221;#ffffff&#8221; button_border_color_hover=&#8221;rgba(0,0,0,0)&#8221; button_border_radius_hover=&#8221;28px&#8221; button_letter_spacing_hover=&#8221;2px&#8221; button_bg_color_hover=&#8221;rgba(0,0,0,0.7)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22header_text_color%22,%22body_text_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;on&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;28px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;2px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0.7)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_cta][et_pb_cta button_url=&#8221;#top&#8221; admin_label=&#8221;Tittle, Paragraph &#038; Call To Action&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;Oswald|||on|||||&#8221; header_font_size=&#8221;45px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Open Sans|600|||||||&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.4em&#8221; use_background_color=&#8221;off&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;10px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Open Sans|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; text_orientation=&#8221;right&#8221; background_layout=&#8221;light&#8221; custom_margin=&#8221;0px|||||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||10px|false|false&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; border_color_left=&#8221;#FFFFFF&#8221; border_width_left_tablet=&#8221;1px&#8221; border_width_left_phone=&#8221;0px&#8221; border_width_left_last_edited=&#8221;on|phone&#8221; button_text_color_hover=&#8221;#ffffff&#8221; button_border_color_hover=&#8221;rgba(0,0,0,0)&#8221; button_border_radius_hover=&#8221;28px&#8221; button_letter_spacing_hover=&#8221;2px&#8221; button_bg_color_hover=&#8221;rgba(0,0,0,0.7)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;on&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;28px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;2px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0.7)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p><a href=\"https:\/\/saaristofestivaali.fi\/\" target=\"_blank\" rel=\"noopener\">Saaristo Festivaali<\/a><\/p>\n<p><a href=\"https:\/\/rantajamit.fi\/\" target=\"_blank\" rel=\"noopener\">Rantajamit<\/a><\/p>\n<p><a href=\"https:\/\/kipinafestival.fi\/\" target=\"_blank\" rel=\"noopener\">Kipin\u00e4 Festival<\/a><\/p>\n<p><a href=\"https:\/\/hiidenkirnufestival.fi\/\" target=\"_blank\" rel=\"noopener\">Hiidenkirnu Festival<\/a><\/p>\n<p><a href=\"https:\/\/karjurock.fi\/\" target=\"_blank\" rel=\"noopener\">Karjurock<\/a><\/p>\n<p><a href=\"https:\/\/www.vauhtiajot.fi\/\" target=\"_blank\" rel=\"noopener\">Vauhtiajot<\/a><\/p>\n<p><a href=\"https:\/\/www.spacefest.fi\/\" target=\"_blank\" rel=\"noopener\">Space Fest<\/a><\/p>\n<p><a href=\"https:\/\/dbtl.fi\/\" target=\"_blank\" rel=\"noopener\">DBTL<\/a><\/p>\n<p><a href=\"https:\/\/smugglerrok.fi\/\" target=\"_blank\" rel=\"noopener\">SmugglerRok<\/a><\/p>\n<p><a href=\"https:\/\/www.tamperecityfestival.fi\/\" target=\"_blank\" rel=\"noopener\">Tampere City Festival<\/a><\/p>\n<p><a href=\"https:\/\/holjat.fi\/\" target=\"_blank\" rel=\"noopener\">Holjat<\/a><\/p>\n<p><a href=\"https:\/\/www.tapiolafestivaali.fi\/\" target=\"_blank\" rel=\"noopener\">Tapiola Festivaali<\/a><\/p>\n<p><a href=\"https:\/\/aurafest.fi\/\" target=\"_blank\" rel=\"noopener\">Aura Fest<\/a><\/p>\n<p><a href=\"https:\/\/salofriendsandmusicfestival.fi\/\" target=\"_blank\" rel=\"noopener\">Salo Friends &amp; Music Festival<\/a><\/p>\n<p><a href=\"https:\/\/www.tapiolafestivaali.fi\/supersunnuntai\/\" target=\"_blank\" rel=\"noopener\">Supersunnuntai<\/a><\/p>\n<p><a href=\"https:\/\/naantalisunfest.fi\/\" target=\"_blank\" rel=\"noopener\">Naantali Sunfest<\/a><\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_video_mp4=&#8221;https:\/\/www.nollapiste.fi\/wp-content\/uploads\/2026\/03\/Nollapiste-mocktail-pudotus-video.mp4&#8243; border_radii=&#8221;off||80px|80px|&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||703px|||&#8221; custom_padding_tablet=&#8221;||703px|||&#8221; custom_padding_phone=&#8221;||350px||false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;9px||8px|||&#8221; box_shadow_style=&#8221;preset5&#8243; box_shadow_blur=&#8221;24px&#8221; box_shadow_spread=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Tittle &#038; Paragraph&#8221; _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;Open Sans|600|||||||&#8221; text_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.7em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_2_font=&#8221;Oswald|||on|||||&#8221; header_2_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_2_font_size=&#8221;36px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-1px|||||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;|||&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;22px||6px|||&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22text_text_color%22,%22header_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>N\u00c4IN NOLLAPISTEEN TARINA SAI ALKUNSA<\/h2>\n<p>Nollapiste syntyi tarpeesta \u2013 alkoholinkulutus on v\u00e4hentynyt ja ihmiset etsiv\u00e4t laadukkaita, kiinnostavia vaihtoehtoja korvaamaan perinteisi\u00e4 alkoholijuomia.<\/p>\n<p>Usein alkoholittomat juomat j\u00e4\u00e4v\u00e4t kuitenkin mehun tasolle, eiv\u00e4tk\u00e4 vastaa niiden kaipaamaa makua, tunnelmaa tai kokemusta. Me p\u00e4\u00e4timme ratkaista t\u00e4m\u00e4n ongelman tarjoamalla klassisia cocktaileja vastaavia mocktaileja, jotka maistuvat aidosti alkoholijuomalta, mutta ovat t\u00e4ysin alkoholittomia.<\/p>\n<p>Meille m\u00e4\u00e4r\u00e4\u00e4 t\u00e4rke\u00e4mp\u00e4\u00e4 on laatu, mist\u00e4 syyst\u00e4 jokainen Nollapisteen-mocktaili on aidosti nautittava.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Tittle &#038; Paragraph&#8221; _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;Open Sans|600|||||||&#8221; text_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_2_font=&#8221;Oswald|||on|||||&#8221; header_2_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; header_2_font_size=&#8221;37px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.4em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;5px||29px||false|&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;0px||22px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-primary-color%22:%91%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22,%22quote_text_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22text_text_color%22,%22header_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Haluatko kuulla kun laajennamme lis\u00e4\u00e4?<\/h2>\n<p>Tilaa uutiskirje ja pysy toiminnassa mukana ajan tasaisesti!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_form captcha=&#8221;off&#8221; email=&#8221;tuuli.almila@remax.fi&#8221; title=&#8221;Tilasi uutiskirjeen Nollapisteen sivuilta&#8221; success_message=&#8221;Uutiskirjeen tilaus onnistui, lis\u00e4\u00e4mme sinut vastaanottajaksi!&#8221; submit_button_text=&#8221;Tilaa&#8221; disabled_on=&#8221;off|off|off&#8221; module_id=&#8221;et_pb_contact_form_0&#8243; _builder_version=&#8221;4.27.6&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; title_text_color=&#8221;RGBA(255,255,255,0)&#8221; title_font_size=&#8221;1px&#8221; form_field_font=&#8221;Open Sans|600|||||||&#8221; form_field_font_size=&#8221;14px&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; button_border_width=&#8221;3px&#8221; button_border_color=&#8221;gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4&#8243; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Open Sans|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_padding=&#8221;14px||||false|false&#8221; custom_padding_tablet=&#8221;50px||||false|false&#8221; custom_padding_phone=&#8221;7px||||false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; title_text_color_tablet=&#8221;RGBA(255,255,255,0)&#8221; title_text_color_phone=&#8221;RGBA(255,255,255,0)&#8221; title_text_color_last_edited=&#8221;on|desktop&#8221; title_font_size_phone=&#8221;1px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;rgba(51,51,51,0.1)&#8221; form_background_color=&#8221;rgba(255,255,255,0.4)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22form_field_text_color%22,%22form_field_text_color%22,%22form_field_text_color%22,%22form_field_text_color%22%93,%22gcid-primary-color%22:%91%22button_bg_color%22,%22button_bg_color%22%93,%22gcid-70b3156a-8c44-4263-a0c6-12c8e19916f4%22:%91%22button_text_color%22,%22button_border_color%22%93}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Nimi&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;S\u00e4hk\u00f6posti&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||10px|||&#8221; border_width_bottom=&#8221;3px&#8221; border_color_bottom=&#8221;gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898&#8243; global_colors_info=&#8221;{%22gcid-81f9b656-ba42-499e-a92c-9ca8a8a8f898%22:%91%22border_color_bottom%22%93}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;||32px|||&#8221; mix_blend_mode=&#8221;multiply&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/share\/19CLoezket\/?mibextid=wwXIfr&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;rgba(160,160,160,0.8)&#8221; custom_margin=&#8221;|2%||2%&#8221; custom_padding=&#8221;12px|12px|12px|12px&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/nollapiste.fi?igsh=MXRjaHRvYWIwMjc2Yw%3D%3D&#038;utm_source=qr&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;rgba(160,160,160,0.8)&#8221; custom_margin=&#8221;|2%||2%&#8221; custom_padding=&#8221;12px|12px|12px|12px&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;tiktok&#8221; url=&#8221;https:\/\/www.tiktok.com\/@nollapiste.fi?is_from_webapp=1&#038;sender_device=pc&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(160,160,160,0.8)&#8221; custom_margin=&#8221;|2%||2%&#8221; custom_padding=&#8221;12px|12px|12px|12px&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]tiktok[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etusivu: Nollapiste tarjoaa laadukkaita ja raikkaita alkoholittomia vaihtoehtoja \u2013 mocktaileja ja mocktail-j\u00e4it\u00e4.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-73","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/pages\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":183,"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"predecessor-version":[{"id":1233,"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/pages\/73\/revisions\/1233"}],"wp:attachment":[{"href":"https:\/\/www.nollapiste.fi\/index.php\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}